{"id":27270,"date":"2025-09-02T11:03:16","date_gmt":"2025-09-02T14:03:16","guid":{"rendered":"https:\/\/infotep.com.ar\/?p=27270"},"modified":"2025-09-02T11:03:17","modified_gmt":"2025-09-02T14:03:17","slug":"matanza-recicla-mas-ecopuntos-para-facilitar-el-cuidado-de-nuestro-ambiente","status":"publish","type":"post","link":"https:\/\/infotep.com.ar\/index.php\/2025\/09\/02\/matanza-recicla-mas-ecopuntos-para-facilitar-el-cuidado-de-nuestro-ambiente\/","title":{"rendered":"<strong>Matanza Recicla: M\u00e1s Ecopuntos para facilitar el cuidado de nuestro ambiente<\/strong>"},"content":{"rendered":"\n<p><em>Una ciudad m\u00e1s limpia, libre de contaminaci\u00f3n y sostenible se logra con un fuerte compromiso de la comunidad. En ese sentido, el Gobierno local pone a disposici\u00f3n de las vecinas y vecinos Ecopuntos, distribu\u00eddos en todas las localidades, para fomentar el reciclaje.<br><br><\/em>Los Ecopuntos son Estaciones Sustentables distribuidas en distintas ciudades del distrito, donde las vecinas y vecinos acercan sus residuos limpios y secos, llev\u00e1ndose una nueva bolsa verde para seguir reciclando. Los materiales que se acopian en los Puntos Verdes son: papel, cart\u00f3n, pl\u00e1sticos, vidrios, metales, envases tetra pak, aceite vegetal usado y peque\u00f1os aparatos electr\u00f3nicos.<br><br>Con el objetivo de fomentar la separaci\u00f3n en origen y promover la econom\u00eda circular en La Matanza, la Subsecretar\u00eda de Ambiente y Desarrollo Sustentable localrelocaliz\u00f3<em>,\u00a0<\/em>adem\u00e1s, el Ecopunto de San Justo en la Delegaci\u00f3n Municipal, ubicada en la calle Marc\u00f3n 3498 esquina Eizaguirre, a la cual las vecinas y vecinos pueden acercarse de 8 a 14 hs.<\/p>\n\n\n\n<p><br><strong>En toda La Matanza, la comunidad cuenta con Ecopuntos<\/strong><\/p>\n\n\n\n<p><br><strong>Aldo Bonzi<\/strong>: Delegaci\u00f3n Municipal Aldo Bonzi, Defensa 1511 de&nbsp; lunes a viernes de 08 a 14 horas.<\/p>\n\n\n\n<p><strong>Villa Luzuriaga<\/strong>: Sociedad de Fomento Argentino del Oeste, Garibaldi 2351, lunes de 08 a 14 horas.&nbsp;<\/p>\n\n\n\n<p>Campo de Deportes J. Newbery, Cuba 720, mi\u00e9rcoles de 08 a 14 horas.<\/p>\n\n\n\n<p>Club 4 de Julio, Mir\u00f3 2200, jueves de 08 a 14 horas.<\/p>\n\n\n\n<p>Centro de D\u00eda Calidoscopio, Thames 333, viernes de 08 a 14 horas.<\/p>\n\n\n\n<p>Plaza Barrio Marina, Berm\u00fadez 2650 de lunes a viernes de 08 a 14 horas.<\/p>\n\n\n\n<p><strong>Ramos Mej\u00eda<\/strong>: Predio Deportivo Ateneo Don Bosco, Bol\u00edvar y Humboldt de lunes a viernes de 08 a 14 horas.<\/p>\n\n\n\n<p>Regi\u00f3n Descentralizada Norte, Av. Rivadavia 13.518 de lunes a viernes de 08 a 14 horas.<\/p>\n\n\n\n<p><strong>Tapiales<\/strong>: Plaza Tapiales, Tuyut\u00ed 1385 de lunes a viernes de 09 a 17 horas.<\/p>\n\n\n\n<p><strong>Lomas del Mirador<\/strong>: Punto Verde Subcomando, Nazca y Av. Gral. San Mart\u00edn de lunes a viernes de 08 a 14 horas.<\/p>\n\n\n\n<p>Casa Joven Diego A. Maradona, Av. Gral. San Mart\u00edn 4332 de lunes a viernes de 10 a 16 horas.<\/p>\n\n\n\n<p><strong>Manzanares:&nbsp;<\/strong>Subdelegaci\u00f3n Manzanares, Carabobo 4590 de lunes y martes de 08 a 14 horas.<\/p>\n\n\n\n<p>Centro de Jubilados San Cayetano, Ambato 196, jueves de 09 a 13 horas.<\/p>\n\n\n\n<p>Planta de clasificaci\u00f3n, Colonia 1551, lunes y martes de 08 a 14 horas.<\/p>\n\n\n\n<p><strong>Rafael Castillo:&nbsp;<\/strong>Delegaci\u00f3n Municipal Rafael Castillo, Estrada 2337 de lunes a viernes de 09 a 14 horas.<\/p>\n\n\n\n<p><strong>Ciudad Evita:&nbsp;<\/strong>Delegaci\u00f3n Municipal Ciudad Evita, Av. G\u00fcemes y El Le\u00f1atero de lunes a viernes de 09 a 12 horas.<\/p>\n\n\n\n<p><strong>La Tablada:&nbsp;<\/strong>Planta de Clasificaci\u00f3n, Arieta 4785, lunes y martes de 08 a 14 horas.<\/p>\n\n\n\n<p>Delegaci\u00f3n Municipal La Tablada, Crovara 3253, lunes y martes de 08 a 14 horas.<\/p>\n\n\n\n<p><strong>G. de Laferrere:&nbsp;<\/strong>Delegaci\u00f3n de Laferrere, Av. Luro 5757 de lunes a viernes de 09 a 14 horas.<\/p>\n\n\n\n<p>Subdelegaci\u00f3n Laferrere Norte, Leonardo Da Vinci 4142 de lunes a viernes | 08 a 14 horas.<\/p>\n\n\n\n<p><strong>Isidro Casanova:&nbsp;<\/strong>Cooperativa Padre Bachi, Sommer 5889 de Lunes a jueves de 09 a 14 horas.<\/p>\n\n\n\n<p>Plaza Hip\u00f3lito Yrigoyen, Rep\u00fablica de Portugal 2802, mi\u00e9rcoles y jueves de 09 a 14 horas.<\/p>\n\n\n\n<p><strong>Gonz\u00e1lez Cat\u00e1n<\/strong>: Delegaci\u00f3n Cat\u00e1n, Cepeda 4321 esq. Ruta 21&nbsp; de lunes a viernes de 09 a 14 horas.<\/p>\n\n\n\n<p>Subdelegaci\u00f3n Cat\u00e1n Este, J. M. de Rosas 16750 de lunes a viernes de 09 a 14 horas<\/p>\n\n\n\n<p>Subdelegaci\u00f3n Cat\u00e1n Sur, San Mat\u00edas 1755 de&nbsp; lunes a viernes de 09 a 14 horas<\/p>\n\n\n\n<p>Descentralizada Sur, J. M. de Rosas 17.798 Km 32 de Lunes a viernes&nbsp; 09 a 14 horas<\/p>\n\n\n\n<p><strong>Virrey del Pino<\/strong>: Cooperativa La Uni\u00f3n, J. M. de Rosas 22.650 de lunes a viernes de 08 a 14 hs<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una ciudad m&aacute;s limpia, libre de contaminaci&oacute;n y sostenible se logra con un fuerte compromiso de la comunidad. En ese sentido, el Gobierno local pone a disposici&oacute;n de las vecinas y vecinos Ecopuntos, distribu&iacute;dos en todas las localidades, para fomentar el reciclaje. Los Ecopuntos son Estaciones Sustentables distribuidas en distintas ciudades del distrito, donde las &hellip; <\/p>\n","protected":false},"author":5,"featured_media":27271,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_joinchat":[]},"categories":[31,26],"tags":[46,43,569],"featured_image_urls":{"full":["https:\/\/infotep.com.ar\/wp-content\/uploads\/2025\/09\/Eco-puntos-MTZ-2.jpeg",1600,1066,false],"thumbnail":["https:\/\/infotep.com.ar\/wp-content\/uploads\/2025\/09\/Eco-puntos-MTZ-2-150x150.jpeg",150,150,true],"medium":["https:\/\/infotep.com.ar\/wp-content\/uploads\/2025\/09\/Eco-puntos-MTZ-2-300x200.jpeg",300,200,true],"medium_large":["https:\/\/infotep.com.ar\/wp-content\/uploads\/2025\/09\/Eco-puntos-MTZ-2-768x512.jpeg",768,512,true],"large":["https:\/\/infotep.com.ar\/wp-content\/uploads\/2025\/09\/Eco-puntos-MTZ-2-1024x682.jpeg",1020,679,true],"1536x1536":["https:\/\/infotep.com.ar\/wp-content\/uploads\/2025\/09\/Eco-puntos-MTZ-2-1536x1023.jpeg",1536,1023,true],"2048x2048":["https:\/\/infotep.com.ar\/wp-content\/uploads\/2025\/09\/Eco-puntos-MTZ-2.jpeg",1600,1066,false],"blossom-feminine-slider":["https:\/\/infotep.com.ar\/wp-content\/uploads\/2025\/09\/Eco-puntos-MTZ-2-1600x649.jpeg",1600,649,true],"blossom-feminine-featured":["https:\/\/infotep.com.ar\/wp-content\/uploads\/2025\/09\/Eco-puntos-MTZ-2-1410x600.jpeg",1410,600,true],"blossom-feminine-with-sidebar":["https:\/\/infotep.com.ar\/wp-content\/uploads\/2025\/09\/Eco-puntos-MTZ-2-1020x600.jpeg",1020,600,true],"blossom-feminine-blog":["https:\/\/infotep.com.ar\/wp-content\/uploads\/2025\/09\/Eco-puntos-MTZ-2-435x435.jpeg",435,435,true],"blossom-feminine-cat":["https:\/\/infotep.com.ar\/wp-content\/uploads\/2025\/09\/Eco-puntos-MTZ-2-450x300.jpeg",450,300,true],"blossom-feminine-related":["https:\/\/infotep.com.ar\/wp-content\/uploads\/2025\/09\/Eco-puntos-MTZ-2-320x200.jpeg",320,200,true],"blossom-feminine-schema":["https:\/\/infotep.com.ar\/wp-content\/uploads\/2025\/09\/Eco-puntos-MTZ-2-90x60.jpeg",90,60,true],"blossom-mommy-blog-slider-big":["https:\/\/infotep.com.ar\/wp-content\/uploads\/2025\/09\/Eco-puntos-MTZ-2-920x650.jpeg",920,650,true],"blossom-mommy-blog-slider":["https:\/\/infotep.com.ar\/wp-content\/uploads\/2025\/09\/Eco-puntos-MTZ-2-460x310.jpeg",460,310,true],"blossom-mommy-blog-two":["https:\/\/infotep.com.ar\/wp-content\/uploads\/2025\/09\/Eco-puntos-MTZ-2-768x480.jpeg",768,480,true]},"author_info":{"info":["Angela Tobar"]},"category_info":"<a href=\"https:\/\/infotep.com.ar\/index.php\/category\/destacadas\/\" rel=\"category tag\">Destacadas<\/a> <a href=\"https:\/\/infotep.com.ar\/index.php\/category\/municipales\/la-matanza\/\" rel=\"category tag\">La Matanza<\/a>","tag_info":"La Matanza","comment_count":"0","_links":{"self":[{"href":"https:\/\/infotep.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/27270"}],"collection":[{"href":"https:\/\/infotep.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infotep.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infotep.com.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/infotep.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=27270"}],"version-history":[{"count":1,"href":"https:\/\/infotep.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/27270\/revisions"}],"predecessor-version":[{"id":27272,"href":"https:\/\/infotep.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/27270\/revisions\/27272"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infotep.com.ar\/index.php\/wp-json\/wp\/v2\/media\/27271"}],"wp:attachment":[{"href":"https:\/\/infotep.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=27270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infotep.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=27270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infotep.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=27270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}